{"id":1051,"date":"2022-03-31T18:07:18","date_gmt":"2022-03-31T16:07:18","guid":{"rendered":"https:\/\/alfioghezzi.com\/?post_type=product&#038;p=1051"},"modified":"2025-09-16T10:30:22","modified_gmt":"2025-09-16T08:30:22","slug":"confettura-di-lamponi","status":"publish","type":"product","link":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/","title":{"rendered":"Confettura di Lamponi"},"content":{"rendered":"<p>Una confettura che racchiude il gusto pieno e verace dei lamponi con un perfetto equilibrio fra dolcezza e acidit\u00e0. Da usare in piccole quantit\u00e0 per colazione, per merenda, ma anche in abbinamento ai formaggi teneri e perfino alla selvaggina.<\/p>\n","protected":false},"excerpt":{"rendered":"Una confettura che racchiude il gusto pieno e verace dei lamponi con un perfetto equilibrio fra dolcezza e acidit\u00e0. Da usare in piccole quantit\u00e0 per colazione, per merenda, ma anche in abbinamento ai formaggi teneri e perfino alla selvaggina.","protected":false},"featured_media":1052,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[38],"product_tag":[],"class_list":{"0":"post-1051","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-confetture","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confettura di Lamponi - Alfio Ghezzi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confettura di Lamponi - Alfio Ghezzi\" \/>\n<meta property=\"og:description\" content=\"Una confettura che racchiude il gusto pieno e verace dei lamponi con un perfetto equilibrio fra dolcezza e acidit\u00e0. Da usare in piccole quantit\u00e0 per colazione, per merenda, ma anche in abbinamento ai formaggi teneri e perfino alla selvaggina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/\" \/>\n<meta property=\"og:site_name\" content=\"Alfio Ghezzi\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T08:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/\",\"url\":\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/\",\"name\":\"Confettura di Lamponi - Alfio Ghezzi\",\"isPartOf\":{\"@id\":\"https:\/\/alfioghezzi.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg\",\"datePublished\":\"2022-03-31T16:07:18+00:00\",\"dateModified\":\"2025-09-16T08:30:22+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/#primaryimage\",\"url\":\"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg\",\"contentUrl\":\"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/alfioghezzi.com\/en\/#website\",\"url\":\"https:\/\/alfioghezzi.com\/en\/\",\"name\":\"Alfio Ghezzi\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/alfioghezzi.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confettura di Lamponi - Alfio Ghezzi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/","og_locale":"en_GB","og_type":"article","og_title":"Confettura di Lamponi - Alfio Ghezzi","og_description":"Una confettura che racchiude il gusto pieno e verace dei lamponi con un perfetto equilibrio fra dolcezza e acidit\u00e0. Da usare in piccole quantit\u00e0 per colazione, per merenda, ma anche in abbinamento ai formaggi teneri e perfino alla selvaggina.","og_url":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/","og_site_name":"Alfio Ghezzi","article_modified_time":"2025-09-16T08:30:22+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/","url":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/","name":"Confettura di Lamponi - Alfio Ghezzi","isPartOf":{"@id":"https:\/\/alfioghezzi.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/#primaryimage"},"image":{"@id":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/#primaryimage"},"thumbnailUrl":"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg","datePublished":"2022-03-31T16:07:18+00:00","dateModified":"2025-09-16T08:30:22+00:00","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/alfioghezzi.com\/en\/prodotto\/confettura-di-lamponi\/#primaryimage","url":"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg","contentUrl":"https:\/\/alfioghezzi.com\/site\/wp-content\/uploads\/antologia-conf-lamponi-A.jpg","width":2000,"height":2000},{"@type":"WebSite","@id":"https:\/\/alfioghezzi.com\/en\/#website","url":"https:\/\/alfioghezzi.com\/en\/","name":"Alfio Ghezzi","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alfioghezzi.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/product\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/media\/1052"}],"wp:attachment":[{"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/media?parent=1051"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/product_brand?post=1051"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/product_cat?post=1051"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/alfioghezzi.com\/en\/wp-json\/wp\/v2\/product_tag?post=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}